{"id":2380,"date":"2024-11-13T07:41:55","date_gmt":"2024-11-13T07:41:55","guid":{"rendered":"https:\/\/finques.nuriapublicitat.com\/politique-de-confidentialite\/"},"modified":"2024-11-13T16:50:52","modified_gmt":"2024-11-13T16:50:52","slug":"politique-de-confidentialite","status":"publish","type":"page","link":"https:\/\/finques.nuriapublicitat.com\/fr\/politique-de-confidentialite\/","title":{"rendered":"Politique de confidentialit\u00e9"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"2380\" class=\"elementor elementor-2380 elementor-2356\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2e6d461 e-flex e-con-boxed e-con e-parent\" data-id=\"2e6d461\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-415a55e elementor-widget elementor-widget-heading\" data-id=\"415a55e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Politique de confidentialit\u00e9<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0cfe367 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"0cfe367\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-44a7c78 e-flex e-con-boxed e-con e-parent\" data-id=\"44a7c78\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f5329a5 elementor-widget elementor-widget-heading\" data-id=\"f5329a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Propri\u00e9t\u00e9 intellectuelle sur le contenu<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a1d90c7 elementor-widget elementor-widget-text-editor\" data-id=\"a1d90c7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Tous les \u00e9l\u00e9ments qui apparaissent sur le site Web, ainsi que la structure, le design et le code source, sont la propri\u00e9t\u00e9 de \u00ab Habitatges Premium ST Andorra, SL \u00bb, ou le cas \u00e9ch\u00e9ant, de tiers qui ont c\u00e9d\u00e9 les droits d&#8217;utilisation correspondants, et qui l&#8217;utilisateur de ce site Internet doit respecter, et est donc prot\u00e9g\u00e9 par la r\u00e9glementation en mati\u00e8re de propri\u00e9t\u00e9 intellectuelle. Les actes de reproduction, modification, distribution ou communication publique du Portail ne peuvent \u00eatre effectu\u00e9s sans l&#8217;accord \u00e9crit pr\u00e9alable du Propri\u00e9taire. L&#8217;acc\u00e8s de l&#8217;utilisateur aux contenus et services du site Web n&#8217;implique aucun droit de transmission, cession, utilisation, modification, exploitation, reproduction, distribution ou communication publique, soumis \u00e0 la propri\u00e9t\u00e9 intellectuelle, sans autorisation pr\u00e9alable et expresse sp\u00e9cifiquement accord\u00e9e \u00e0 cet effet. finalit\u00e9 par le Propri\u00e9taire ou le tiers titulaire des droits, le cas \u00e9ch\u00e9ant. Les utilisateurs du site Web ne pourront faire qu&#8217;un usage priv\u00e9 et personnel de son contenu, c&#8217;est-\u00e0-dire qu&#8217;ils auront uniquement le droit de visualiser et de faire des copies du contenu pour leur usage personnel et exclusif et devront appliquer ces droits en fonction des les principes de bonne foi et la r\u00e9glementation applicable. L&#8217;utilisation du site Internet ou de l&#8217;un des \u00e9l\u00e9ments \u00e0 des fins commerciales ou ill\u00e9gales est absolument interdite. L&#8217;utilisation non autoris\u00e9e des informations contenues dans ce site Web, ainsi que les dommages caus\u00e9s aux droits de propri\u00e9t\u00e9 intellectuelle, peuvent donner lieu \u00e0 l&#8217;exercice d&#8217;actions en justice pertinentes et, le cas \u00e9ch\u00e9ant, aux responsabilit\u00e9s d\u00e9riv\u00e9es dudit exercice.     <\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-83eb91f e-flex e-con-boxed e-con e-parent\" data-id=\"83eb91f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-042354b elementor-widget elementor-widget-heading\" data-id=\"042354b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Protection des donn\u00e9es<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-afad0e5 elementor-widget elementor-widget-text-editor\" data-id=\"afad0e5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"default_cursor_cs\">Conform\u00e9ment \u00e0 la loi 15\/2003 du 18 d\u00e9cembre, qualifi\u00e9e de protection des donn\u00e9es personnelles, les utilisateurs sont inform\u00e9s de ce qui suit :<\/p>\n<p class=\"default_cursor_cs\">La visite du site Web est anonyme. Toutefois, dans le but d&#8217;offrir un meilleur service et de faciliter l&#8217;utilisation du site Internet, le nombre de pages visit\u00e9es, le nombre de visites, ainsi que l&#8217;activit\u00e9 des visiteurs sur le site Internet et leur fr\u00e9quence d&#8217;utilisation, \u00e0 l&#8217;aide de l&#8217;outil Google Analytics . <\/p>\n<p class=\"default_cursor_cs\">Nous n&#8217;identifions pas personnellement l&#8217;utilisateur \u2013 nous ne stockons pas d&#8217;informations relatives aux noms, num\u00e9ros d&#8217;identification, e-mails ou similaires ; ou des donn\u00e9es qui peuvent identifier de mani\u00e8re permanente un appareil particulier, comme le num\u00e9ro d&#8217;identification de l&#8217;appareil.<\/p>\n<p class=\"default_cursor_cs\">En outre, le site Web propose des processus d&#8217;inscription des utilisateurs, des contacts, des concours et des campagnes de marketing \u00e0 travers lesquelles sont collect\u00e9es des donn\u00e9es personnelles des utilisateurs qui feront partie du fichier de l&#8217;entreprise, g\u00e9r\u00e9 par \u00ab Habitatges Premium ST Andorra, SL \u00bb. Les donn\u00e9es personnelles collect\u00e9es \u00e0 travers ces processus, concours ou campagnes peuvent \u00eatre transf\u00e9r\u00e9es \u00e0 des soci\u00e9t\u00e9s tierces qui collaborent avec Andorra Sotheby&#8217;s International Realty pour l&#8217;envoi d&#8217;informations, d&#8217;actualit\u00e9s, de publicit\u00e9s et toute autre activit\u00e9 li\u00e9e \u00e0 Andorra Sotheby&#8217;s International Realty pour tout support ou canal. d&#8217;informations. Lorsque l&#8217;utilisateur participe \u00e0 ces processus, concours ou campagnes, Andorra Sotheby&#8217;s International Realty, SAU sauvegardera les donn\u00e9es personnelles demand\u00e9es et prendra les mesures n\u00e9cessaires pour \u00e9viter leur alt\u00e9ration, perte, traitement ou acc\u00e8s non autoris\u00e9, conform\u00e9ment \u00e0 ce qui est \u00e9tabli par la r\u00e9glementation applicable. Dans ces cas, il sera de l&#8217;obligation de l&#8217;utilisateur de maintenir les donn\u00e9es \u00e0 jour afin qu&#8217;elles correspondent \u00e0 tout moment \u00e0 la r\u00e9alit\u00e9 et l&#8217;utilisateur pourra exercer les droits reconnus par la loi et, en particulier, les droits d&#8217;acc\u00e8s, de rectification, d&#8217;opposition et suppression de vos donn\u00e9es personnelles, ainsi que le droit de r\u00e9voquer le consentement donn\u00e9 pour le transfert des donn\u00e9es. Ces droits peuvent \u00eatre exerc\u00e9s par l&#8217;int\u00e9ress\u00e9 ou, le cas \u00e9ch\u00e9ant, par quiconque le repr\u00e9sente.    <\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7e2a329 e-flex e-con-boxed e-con e-parent\" data-id=\"7e2a329\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8e9bbed elementor-widget elementor-widget-heading\" data-id=\"8e9bbed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">engagements<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1d4415d elementor-widget elementor-widget-text-editor\" data-id=\"1d4415d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"default_cursor_cs\">Le Propri\u00e9taire s&#8217;engage \u00e0 ne pas faire de publicit\u00e9 trompeuse. A cet \u00e9gard, les erreurs formelles ou num\u00e9riques qui pourraient se trouver dans le contenu des diff\u00e9rentes sections du site en raison d&#8217;une maintenance et\/ou d&#8217;une mise \u00e0 jour incompl\u00e8te ou d\u00e9fectueuse des informations contenues dans ces sections du site ne seront pas consid\u00e9r\u00e9es comme de la publicit\u00e9 trompeuse. web \u00e0 la suite de ce qui est mentionn\u00e9 dans cette section, et le Propri\u00e9taire s&#8217;engage \u00e0 corriger cette situation lorsqu&#8217;il aura connaissance de ces erreurs. Il s&#8217;engage \u00e9galement \u00e0 ne pas envoyer de communications commerciales sans les identifier.  <\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e15e9ac e-flex e-con-boxed e-con e-parent\" data-id=\"e15e9ac\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9cbf8dc elementor-widget elementor-widget-heading\" data-id=\"9cbf8dc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Cookies<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c79c8b7 elementor-widget elementor-widget-text-editor\" data-id=\"c79c8b7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"default_cursor_cs\">Le site Internet utilise des cookies qui sont stock\u00e9s sur l&#8217;ordinateur de l&#8217;utilisateur. Les cookies sont de petits fichiers que le serveur envoie aux ordinateurs des utilisateurs mais qui ne fournissent aucune information personnelle. Le serveur sur lequel le site est h\u00e9berg\u00e9 reconna\u00eet automatiquement l&#8217;adresse IP de l&#8217;ordinateur du client et\/ou de l&#8217;utilisateur, le jour et l&#8217;heure d&#8217;\u00e9tablissement et de fin de la connexion, ainsi que les informations sur les diff\u00e9rentes rubriques consult\u00e9es. Il est n\u00e9cessaire que le serveur connaisse ces donn\u00e9es pour pouvoir communiquer.   <\/p>\n<p class=\"default_cursor_cs\">L&#8217;utilisateur peut configurer son navigateur pour avertir de la pr\u00e9sence de cookies. De m\u00eame, l&#8217;utilisateur peut configurer son navigateur pour qu&#8217;il ne re\u00e7oive pas ces cookies, puisque cette action ne l&#8217;emp\u00eachera pas d&#8217;acc\u00e9der aux informations du site. <\/p>\n<p class=\"default_cursor_cs\">Dans tous les cas, l&#8217;acc\u00e8s au site implique l&#8217;acceptation par l&#8217;utilisateur des cookies indiqu\u00e9s ci-dessus et de tout autre qui, pour des raisons techniques, organisationnelles ou autres, pourrait \u00eatre pr\u00e9sent.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c8fb3e2 e-flex e-con-boxed e-con e-parent\" data-id=\"c8fb3e2\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5a92bf1 elementor-widget elementor-widget-heading\" data-id=\"5a92bf1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Politiques d'utilisation<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-94362a0 elementor-widget elementor-widget-text-editor\" data-id=\"94362a0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"default_cursor_cs\">L&#8217;utilisateur est responsable du respect des lois et r\u00e9glementations en vigueur et des r\u00e8gles applicables \u00e0 l&#8217;utilisation faite des produits et applications. De m\u00eame, est interdite l&#8217;utilisation du site Internet contraire \u00e0 la bonne foi, notamment et de mani\u00e8re non exhaustive : utilisation contraire \u00e0 la r\u00e9glementation andorrane ou portant atteinte aux droits de tiers ; la publication ou la transmission de tout contenu violent, obsc\u00e8ne, injurieux, ill\u00e9gal, racial, x\u00e9nophobe ou diffamatoire ; modifier ou intervenir par des moyens frauduleux sur des pages Web personnelles, des e-mails ou des syst\u00e8mes d&#8217;autres utilisateurs ou de tiers sans leur autorisation ; les cracks, les num\u00e9ros de s\u00e9rie de programmes ou tout autre contenu portant atteinte aux droits de propri\u00e9t\u00e9 intellectuelle de tiers ; la collecte et\/ou l&#8217;utilisation de donn\u00e9es personnelles d&#8217;autres utilisateurs sans leur consentement expr\u00e8s ou en violation des dispositions de la loi qualifi\u00e9e 15\/2003 sur la protection des donn\u00e9es personnelles ; l&#8217;utilisation du serveur de messagerie, du domaine et des adresses e-mail \u00e0 des fins de spamming, mail bombing, usurpation d&#8217;identit\u00e9, fraude \u00e0 la garde de tiers, Scam 419, pharming, propagation de virus (chevaux de Troie, etc.) ou tout autre type d&#8217;activit\u00e9 r\u00e9alis\u00e9e avec intention frauduleuse ou criminelle. L&#8217;utilisateur est seul responsable du contenu des donn\u00e9es et informations transmises et stock\u00e9es dans des espaces contract\u00e9s ou autoris\u00e9s non g\u00e9r\u00e9s par le Web, ainsi que des hyperliens, des r\u00e9clamations de tiers et des actions en justice pouvant affecter la propri\u00e9t\u00e9 intellectuelle, les droits de la personnalit\u00e9, protection des donn\u00e9es et tout autre. Il est express\u00e9ment interdit d&#8217;acc\u00e9der, de modifier, de visualiser la configuration, la structure et les fichiers des serveurs web. Face \u00e0 tout probl\u00e8me pouvant survenir dans les serveurs et les syst\u00e8mes de s\u00e9curit\u00e9 du Web comme cons\u00e9quence directe d&#8217;une action n\u00e9gligente de l&#8217;utilisateur, celui-ci sera responsable de la responsabilit\u00e9 civile et p\u00e9nale correspondante. L&#8217;utilisateur respectera les normes techniques fix\u00e9es par le Web dans l&#8217;administration et le d\u00e9veloppement des produits utilis\u00e9s afin qu&#8217;il n&#8217;y ait pas d&#8217;utilisation abusive qui retarderait les serveurs et porterait atteinte \u00e0 la fourniture des produits ou aux droits des autres utilisateurs.     <\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-60edbb7 e-flex e-con-boxed e-con e-parent\" data-id=\"60edbb7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5a6176e elementor-widget elementor-widget-heading\" data-id=\"5a6176e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Droit d'auteur<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ff68eb8 elementor-widget elementor-widget-text-editor\" data-id=\"ff68eb8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"default_cursor_cs\">Tous les droits d\u00e9riv\u00e9s de la propri\u00e9t\u00e9 intellectuelle sont express\u00e9ment r\u00e9serv\u00e9s par le Propri\u00e9taire. Le code source, les graphismes, les photographies, la musique, les sons, les animations, les logiciels, les textes, les noms de domaine, les marques, ainsi que les informations et contenus collect\u00e9s sur le Web sont prot\u00e9g\u00e9s par la l\u00e9gislation andorrane en faveur du Propri\u00e9taire. Le Propri\u00e9taire n&#8217;autorise pas, en tout ou en partie, la reproduction, la publication, le traitement informatique, la distribution, la diffusion, la modification, la transformation ou la d\u00e9compilation sans autorisation \u00e9crite pr\u00e9alable. L&#8217;utilisateur ne peut utiliser le mat\u00e9riel figurant sur le site que pour un usage personnel et priv\u00e9. L&#8217;utilisation \u00e0 des fins commerciales ou toute autre utilisation non personnelle et priv\u00e9e est interdite. Le Propri\u00e9taire veillera au respect des conditions ci-dessus ainsi qu&#8217;au bon usage de sa propri\u00e9t\u00e9 intellectuelle et industrielle, en engageant toutes les actions judiciaires appropri\u00e9es. Le Propri\u00e9taire peut modifier, sans pr\u00e9avis, les informations contenues sur le site Internet, ainsi que sa configuration et sa pr\u00e9sentation.      <\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1cfc8ce e-flex e-con-boxed e-con e-parent\" data-id=\"1cfc8ce\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d5b7e4b elementor-widget elementor-widget-heading\" data-id=\"d5b7e4b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">acceptation<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-24de7fd elementor-widget elementor-widget-text-editor\" data-id=\"24de7fd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"default_cursor_cs\">L&#8217;acc\u00e8s et l&#8217;utilisation du site Internet impliquent le consentement, l&#8217;acceptation et l&#8217;adh\u00e9sion de l&#8217;utilisateur aux conditions d\u00e9taill\u00e9es ci-dessus.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-821c72c e-flex e-con-boxed e-con e-parent\" data-id=\"821c72c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6dcd565 elementor-widget elementor-widget-heading\" data-id=\"6dcd565\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">L\u00e9gislation applicable et juridiction<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7a3c5b2 elementor-widget elementor-widget-text-editor\" data-id=\"7a3c5b2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"default_cursor_cs\">Ces conditions d&#8217;acc\u00e8s sont soumises au syst\u00e8me juridique andorran et \u00e0 ses tribunaux.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Politique de confidentialit\u00e9 Propri\u00e9t\u00e9 intellectuelle sur le contenu Tous les \u00e9l\u00e9ments qui apparaissent sur le site Web, ainsi que la structure, le design et le code source, sont la propri\u00e9t\u00e9 de \u00ab Habitatges Premium ST Andorra, SL \u00bb, ou le cas \u00e9ch\u00e9ant, de tiers qui ont c\u00e9d\u00e9 les droits d&#8217;utilisation correspondants, et qui l&#8217;utilisateur de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"content-type":"","footnotes":""},"class_list":["post-2380","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/finques.nuriapublicitat.com\/fr\/wp-json\/wp\/v2\/pages\/2380","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/finques.nuriapublicitat.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/finques.nuriapublicitat.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/finques.nuriapublicitat.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/finques.nuriapublicitat.com\/fr\/wp-json\/wp\/v2\/comments?post=2380"}],"version-history":[{"count":3,"href":"https:\/\/finques.nuriapublicitat.com\/fr\/wp-json\/wp\/v2\/pages\/2380\/revisions"}],"predecessor-version":[{"id":2498,"href":"https:\/\/finques.nuriapublicitat.com\/fr\/wp-json\/wp\/v2\/pages\/2380\/revisions\/2498"}],"wp:attachment":[{"href":"https:\/\/finques.nuriapublicitat.com\/fr\/wp-json\/wp\/v2\/media?parent=2380"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}