{"id":3352,"date":"2024-11-18T10:19:00","date_gmt":"2024-11-18T10:19:00","guid":{"rendered":"https:\/\/finques.nuriapublicitat.com\/propietats\/maison-roustique-charmante-a-serrat\/"},"modified":"2024-11-18T10:32:09","modified_gmt":"2024-11-18T10:32:09","slug":"maison-roustique-charmante-a-serrat","status":"publish","type":"property","link":"https:\/\/finques.nuriapublicitat.com\/fr\/propietats\/maison-roustique-charmante-a-serrat\/","title":{"rendered":"Charmante Maison Roustique \u00e0 Serrat"},"content":{"rendered":"<p>D\u00e9couvrez cette <strong>charmante maison roustique andorrane<\/strong> : un <strong>refuge<\/strong> unique <strong>en pleine nature<\/strong><\/p>\n<p>Nous vous pr\u00e9sentons une propri\u00e9t\u00e9 exclusive de 120 m\u00b2 qui allie <strong>le charme rustique montagnard<\/strong> \u00e0 tout le confort moderne. Situ\u00e9 dans un <strong>environnement naturel et ensoleill\u00e9<\/strong> , ce bateau est id\u00e9al pour ceux qui recherchent la tranquillit\u00e9 et une connexion authentique avec la nature. <\/p>\n<p>Au rez-de-chauss\u00e9e se trouve un confortable salon-salle \u00e0 manger pr\u00e9sid\u00e9 par une impressionnante chemin\u00e9e en pierre, parfaite pour cr\u00e9er une <strong>atmosph\u00e8re chaleureuse<\/strong> pendant les froids hivers andorrans. La cuisine rustique, enti\u00e8rement \u00e9quip\u00e9e, a \u00e9t\u00e9 con\u00e7ue pour offrir confort et fonctionnalit\u00e9 sans perdre son essence traditionnelle. <\/p>\n<p>La zone nuit abrite deux grandes chambres doubles avec vue ext\u00e9rieure et une salle de bain compl\u00e8te. Chaque d\u00e9tail de la maison refl\u00e8te la qualit\u00e9 et le style : parquets impeccables, isolation thermique performante et fen\u00eatres climatis\u00e9es qui assurent le confort \u00e0 tout moment de l&#8217;ann\u00e9e. <\/p>\n<p>Cette maison roustique est plus qu&#8217;une habitation : c&#8217;est une maison con\u00e7ue pour ceux qui appr\u00e9cient l&#8217;authenticit\u00e9, la s\u00e9r\u00e9nit\u00e9 de la montagne et le luxe des petits d\u00e9tails.<\/p>\n<p><strong> <\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>D\u00e9couvrez cette charmante maison roustique andorrane : un refuge unique en pleine nature Nous vous pr\u00e9sentons une propri\u00e9t\u00e9 exclusive de 120 m\u00b2 qui allie le charme rustique montagnard \u00e0 tout le confort moderne. Situ\u00e9 dans un environnement naturel et ensoleill\u00e9 , ce bateau est id\u00e9al pour ceux qui recherchent la tranquillit\u00e9 et une connexion authentique [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":3288,"parent":0,"menu_order":0,"template":"","property_type":[440],"property_status":[226],"property_feature":[426,400,430],"property_label":[],"property_state":[252],"property_city":[283],"class_list":["post-3352","property","type-property","status-publish","has-post-thumbnail","hentry","property_type-maison-roustique","property_status-louer","property_feature-armoires-murales","property_feature-parking-fr","property_feature-vues-sur-la-montagne","property_state-ordino-fr","property_city-el-serrat-fr"],"property_meta":{"fave_featured":["0"],"houzez_featured_listing_date":[""],"fave_property_images":["3286","3290","3294","3298","3302","3306","3310","3314","3318","3322","3326","3330","3334","3338","3342","3346"],"_top_nav_excluded":[""],"_cms_nav_minihome":[""],"_thumbnail_id":["3288"],"_last_translation_edit_mode":["translation-editor"],"fave_property_price":["2000"],"fave_property_size":["120"],"fave_property_size_prefix":["m\u00b2"],"fave_property_land_postfix":["m\u00b2"],"fave_property_bedrooms":["2"],"fave_property_bathrooms":["1"],"fave_property_garage":["2"],"fave_property_id":["6169"],"fave_agent_display_option":["author_info"],"additional_features":["a:1:{i:0;a:2:{s:29:\"fave_additional_feature_title\";s:0:\"\";s:29:\"fave_additional_feature_value\";s:0:\"\";}}"],"floor_plans":["a:1:{i:0;a:8:{s:15:\"fave_plan_title\";s:0:\"\";s:15:\"fave_plan_rooms\";s:0:\"\";s:19:\"fave_plan_bathrooms\";s:0:\"\";s:15:\"fave_plan_price\";s:0:\"\";s:23:\"fave_plan_price_postfix\";s:0:\"\";s:14:\"fave_plan_size\";s:0:\"\";s:15:\"fave_plan_image\";s:0:\"\";s:21:\"fave_plan_description\";s:0:\"\";}}"],"_elementor_page_assets":["a:0:{}"]},"_links":{"self":[{"href":"https:\/\/finques.nuriapublicitat.com\/fr\/wp-json\/wp\/v2\/properties\/3352","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/finques.nuriapublicitat.com\/fr\/wp-json\/wp\/v2\/properties"}],"about":[{"href":"https:\/\/finques.nuriapublicitat.com\/fr\/wp-json\/wp\/v2\/types\/property"}],"author":[{"embeddable":true,"href":"https:\/\/finques.nuriapublicitat.com\/fr\/wp-json\/wp\/v2\/users\/8"}],"version-history":[{"count":1,"href":"https:\/\/finques.nuriapublicitat.com\/fr\/wp-json\/wp\/v2\/properties\/3352\/revisions"}],"predecessor-version":[{"id":3354,"href":"https:\/\/finques.nuriapublicitat.com\/fr\/wp-json\/wp\/v2\/properties\/3352\/revisions\/3354"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/finques.nuriapublicitat.com\/fr\/wp-json\/wp\/v2\/media\/3288"}],"wp:attachment":[{"href":"https:\/\/finques.nuriapublicitat.com\/fr\/wp-json\/wp\/v2\/media?parent=3352"}],"wp:term":[{"taxonomy":"property_type","embeddable":true,"href":"https:\/\/finques.nuriapublicitat.com\/fr\/wp-json\/wp\/v2\/property_type?post=3352"},{"taxonomy":"property_status","embeddable":true,"href":"https:\/\/finques.nuriapublicitat.com\/fr\/wp-json\/wp\/v2\/property_status?post=3352"},{"taxonomy":"property_feature","embeddable":true,"href":"https:\/\/finques.nuriapublicitat.com\/fr\/wp-json\/wp\/v2\/property_feature?post=3352"},{"taxonomy":"property_label","embeddable":true,"href":"https:\/\/finques.nuriapublicitat.com\/fr\/wp-json\/wp\/v2\/property_label?post=3352"},{"taxonomy":"property_state","embeddable":true,"href":"https:\/\/finques.nuriapublicitat.com\/fr\/wp-json\/wp\/v2\/property_state?post=3352"},{"taxonomy":"property_city","embeddable":true,"href":"https:\/\/finques.nuriapublicitat.com\/fr\/wp-json\/wp\/v2\/property_city?post=3352"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}